{"id":798,"date":"2021-02-12T13:10:35","date_gmt":"2021-02-12T11:10:35","guid":{"rendered":"https:\/\/ainogalleria.fi\/teoskauppa\/?post_type=product&#038;p=798"},"modified":"2021-03-03T09:56:53","modified_gmt":"2021-03-03T07:56:53","slug":"rodolfo-medina-89-loistokkuus-4-splendor-4","status":"publish","type":"product","link":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/","title":{"rendered":"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4"},"content":{"rendered":"<p>Photo print on CAPA plastic board or aluminium composite<br \/>\nwidth: 60 \/ 80 \/ 90 cm<\/p>\n<p>Valokuva painettuna CAPA muovilevylle tai alumiinikomposiitille<br \/>\nleveys: 60 \/ 80 \/ 90 cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rodolfo Medina \u2013 Pampa Horizons photoprint<\/p>\n<p>Rodolfo Medina &#8211; Pampa Horizons valokuvatuloste<\/p>\n<p>Width\/leveys: 60 \/ 80 \/ 90 cm<\/p>\n","protected":false},"featured_media":805,"template":"","meta":[],"product_brand":[],"product_cat":[26,16],"product_tag":[],"class_list":{"0":"post-798","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pampa-horizons","7":"product_cat-photo-prints","9":"first","10":"instock","11":"taxable","12":"shipping-taxable","13":"purchasable","14":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/\" \/>\n<meta property=\"og:locale\" content=\"fi_FI\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa\" \/>\n<meta property=\"og:description\" content=\"Rodolfo Medina \u2013 Pampa Horizons photoprint  Rodolfo Medina - Pampa Horizons valokuvatuloste  Width\/leveys: 60 \/ 80 \/ 90 cm\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/\" \/>\n<meta property=\"og:site_name\" content=\"AINO GALLERIA teoskauppa\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Galleria-Aino-671946403253203\/\" \/>\n<meta property=\"article:modified_time\" content=\"2021-03-03T07:56:53+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2021\/02\/IMG_6321-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1013\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/\",\"url\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/\",\"name\":\"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/IMG_6321-1.jpg\",\"datePublished\":\"2021-02-12T11:10:35+00:00\",\"dateModified\":\"2021-03-03T07:56:53+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/#breadcrumb\"},\"inLanguage\":\"fi\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/IMG_6321-1.jpg\",\"contentUrl\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/02\\\/IMG_6321-1.jpg\",\"width\":1500,\"height\":1013},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/teos\\\/rodolfo-medina-89-loistokkuus-4-splendor-4\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"AINO GALLERIA teoskauppa\",\"item\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#website\",\"url\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/\",\"name\":\"AINO GALLERIA teoskauppa\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fi\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#organization\",\"name\":\"AINO GALLERIA\",\"url\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fi\",\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/aino-galleria-logo.png\",\"contentUrl\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/10\\\/aino-galleria-logo.png\",\"width\":302,\"height\":53,\"caption\":\"AINO GALLERIA\"},\"image\":{\"@id\":\"https:\\\/\\\/ainogalleria.fi\\\/teoskauppa\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Galleria-Aino-671946403253203\\\/\",\"https:\\\/\\\/www.instagram.com\\\/ainogalleria\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/","og_locale":"fi_FI","og_type":"article","og_title":"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa","og_description":"Rodolfo Medina \u2013 Pampa Horizons photoprint  Rodolfo Medina - Pampa Horizons valokuvatuloste  Width\/leveys: 60 \/ 80 \/ 90 cm","og_url":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/","og_site_name":"AINO GALLERIA teoskauppa","article_publisher":"https:\/\/www.facebook.com\/Galleria-Aino-671946403253203\/","article_modified_time":"2021-03-03T07:56:53+00:00","og_image":[{"width":1500,"height":1013,"url":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2021\/02\/IMG_6321-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/","url":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/","name":"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4 - AINO GALLERIA teoskauppa","isPartOf":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/#primaryimage"},"image":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/#primaryimage"},"thumbnailUrl":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2021\/02\/IMG_6321-1.jpg","datePublished":"2021-02-12T11:10:35+00:00","dateModified":"2021-03-03T07:56:53+00:00","breadcrumb":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/#breadcrumb"},"inLanguage":"fi","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/"]}]},{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/#primaryimage","url":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2021\/02\/IMG_6321-1.jpg","contentUrl":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2021\/02\/IMG_6321-1.jpg","width":1500,"height":1013},{"@type":"BreadcrumbList","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/teos\/rodolfo-medina-89-loistokkuus-4-splendor-4\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/ainogalleria.fi\/teoskauppa\/"},{"@type":"ListItem","position":2,"name":"AINO GALLERIA teoskauppa","item":"https:\/\/ainogalleria.fi\/teoskauppa\/"},{"@type":"ListItem","position":3,"name":"Rodolfo Medina: 89. Loistokkuus 4 \u2013 SPLENDOR 4"}]},{"@type":"WebSite","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#website","url":"https:\/\/ainogalleria.fi\/teoskauppa\/","name":"AINO GALLERIA teoskauppa","description":"","publisher":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ainogalleria.fi\/teoskauppa\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fi"},{"@type":"Organization","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#organization","name":"AINO GALLERIA","url":"https:\/\/ainogalleria.fi\/teoskauppa\/","logo":{"@type":"ImageObject","inLanguage":"fi","@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#\/schema\/logo\/image\/","url":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2020\/10\/aino-galleria-logo.png","contentUrl":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-content\/uploads\/sites\/2\/2020\/10\/aino-galleria-logo.png","width":302,"height":53,"caption":"AINO GALLERIA"},"image":{"@id":"https:\/\/ainogalleria.fi\/teoskauppa\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Galleria-Aino-671946403253203\/","https:\/\/www.instagram.com\/ainogalleria"]}]}},"_links":{"self":[{"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/product\/798","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/media\/805"}],"wp:attachment":[{"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/media?parent=798"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/product_brand?post=798"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/product_cat?post=798"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ainogalleria.fi\/teoskauppa\/wp-json\/wp\/v2\/product_tag?post=798"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}